{"id":1989,"date":"2021-11-08T11:32:56","date_gmt":"2021-11-08T16:32:56","guid":{"rendered":"https:\/\/www.dawsoncollege.qc.ca\/research\/?p=1989"},"modified":"2021-11-08T11:32:56","modified_gmt":"2021-11-08T16:32:56","slug":"des-consultations-inspirantes-un-plan-porteur-450-m-investis","status":"publish","type":"post","link":"https:\/\/www.dawsoncollege.qc.ca\/research\/des-consultations-inspirantes-un-plan-porteur-450-m-investis\/","title":{"rendered":"Des consultations inspirantes, un plan porteur, 450 M$ investis"},"content":{"rendered":"<p>Plus que jamais la r\u00e9ussite est \u00e0 l\u2019ordre du jour de l\u2019enseignement sup\u00e9rieur. Pensons au r\u00e9cent rapport de F\u00e9d\u00e9ration des c\u00e9geps :\u00a0<u>La r\u00e9ussite : regards r\u00e9trospectifs et prospectifs.<\/u>\u00a0R\u00e9f\u00e9rons-nous aussi aux travaux entourant le Chantier sur la r\u00e9ussite en enseignement sup\u00e9rieur notamment aux m\u00e9moires d\u00e9pos\u00e9s en f\u00e9vrier dernier lors de cette consultation.<\/p>\n<p>Dans cette foul\u00e9e, le minist\u00e8re de l\u2019Enseignement sup\u00e9rieur (MES) lan\u00e7ait, le 2 septembre 2021, son\u00a0<u>Plan d\u2019action pour la r\u00e9ussite en enseignement sup\u00e9rieur 2021-2026.\u00a0<\/u>Un plan d\u2019action qui pre\u0301voit des investissements de 450 M$ sur 5 ans, dont 175 M$ consacr\u00e9s sp\u00e9cifiquement au r\u00e9seau coll\u00e9gial.<\/p>\n<p>&nbsp;<\/p>\n<p>To read more, please <a href=\"http:\/\/www.lescegeps.com\/pedagogie\/apprentissage_et_reussite_scolaire\/des_consultations_inspirantes_un_plan_porteur_450_m_investis\" target=\"_blank\" rel=\"noopener noreferrer\">click here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus que jamais la r\u00e9ussite est \u00e0 l\u2019ordre du jour de l\u2019enseignement sup\u00e9rieur. Pensons au r\u00e9cent rapport de F\u00e9d\u00e9ration des c\u00e9geps :\u00a0La r\u00e9ussite : regards r\u00e9trospectifs et prospectifs.\u00a0R\u00e9f\u00e9rons-nous aussi aux travaux entourant le Chantier sur la r\u00e9ussite en enseignement sup\u00e9rieur notamment aux m\u00e9moires d\u00e9pos\u00e9s en f\u00e9vrier dernier lors de cette consultation. Dans cette foul\u00e9e, le&#8230;<\/p>\n","protected":false},"author":0,"featured_media":1990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,1],"tags":[],"class_list":["post-1989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcement","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/posts\/1989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/comments?post=1989"}],"version-history":[{"count":1,"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/posts\/1989\/revisions"}],"predecessor-version":[{"id":1991,"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/posts\/1989\/revisions\/1991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/media\/1990"}],"wp:attachment":[{"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/media?parent=1989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/categories?post=1989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dawsoncollege.qc.ca\/research\/wp-json\/wp\/v2\/tags?post=1989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}